{"id":6419,"date":"2022-09-15T13:35:05","date_gmt":"2022-09-15T12:35:05","guid":{"rendered":"https:\/\/www.gs-carbotech.com\/product\/tail-light-cover\/"},"modified":"2022-10-21T13:22:10","modified_gmt":"2022-10-21T12:22:10","slug":"copertura-della-luce-posteriore","status":"publish","type":"product","link":"https:\/\/www.gs-carbotech.com\/it\/prodotto\/copertura-della-luce-posteriore\/","title":{"rendered":"COPERTURA DELLA LUCE POSTERIORE"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<table class=\"desc-table\" data-id=\"07-DCM-HY-154\">\n<tbody>\n<tr>\n<td class=\"heading\">Si adatta per:<\/td>\n<td>Ducati Hypermotard 1100 2007-2009, 1100 EVO 2010-2012, 1100 EVO SP 2010-2012, 1100 S 2007-2009, 796 2010-2012<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Tecnologia:<\/td>\n<td>autoclave\/prepreg<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Materiale:<\/td>\n<td>100% carbonio prepreg di alta qualit\u00e0<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Finitura superficiale:<\/td>\n<td>finitura brillante &#038; mat<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Rivestimento:<\/td>\n<td>la laccatura della ceramica conferisce una protezione permanente, resistenza agli UV, resistenza chimica al 100%, una durezza molto elevata, la resistenza a colpi, abrasioni e graffi e protegge la superficie dall&#8217;acqua e dallo sporco<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Altre caratteristiche:<\/td>\n<td>sostituisce il componente originale usando i punti di fissaggio originali | montaggio preciso, senza ulteriore foratura o rettifica | leggero ma rigido e resistente | tessuto coerente, lo stesso di Ducati Performance | niente fori nella finitura<\/td>\n<\/tr>\n<tr>\n<td class=\"heading\">Disponibilit\u00e0:<\/td>\n<td>in magazzino | possibilit\u00e0 di spedizione entro 4 giorni lavorativi<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[83,93],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/product\/6419"}],"collection":[{"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/comments?post=6419"}],"wp:attachment":[{"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/media?parent=6419"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/product_cat?post=6419"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gs-carbotech.com\/it\/wp-json\/wp\/v2\/product_tag?post=6419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}